{"id":3397,"date":"2016-09-08T10:38:20","date_gmt":"2016-09-08T15:08:20","guid":{"rendered":"https:\/\/milibrohispano.org\/?p=3397"},"modified":"2016-09-08T10:42:49","modified_gmt":"2016-09-08T15:12:49","slug":"aipeh-pr-se-une-a-celebracion-internacional-mes-libro-hispano-2016","status":"publish","type":"post","link":"https:\/\/milibrohispano.org\/en\/aipeh-pr-se-une-a-celebracion-internacional-mes-libro-hispano-2016\/","title":{"rendered":"AIPEH Puerto Rico se une a Celebraci\u00f3n Internacional del Mes del Libro Hispano 2016"},"content":{"rendered":"<p style=\"text-align: justify;\">Como en a\u00f1os anteriores, AIPEH-PR se ha unido a la celebraci\u00f3n del Libro Hispano comprendido entre el 15 de septiembre y el 15 de octubre.<\/p>\n<p style=\"text-align: justify;\">La Celebraci\u00f3n Internacional del Mes del Libro Hispano\u00a9 es una festividad sin fines de lucro, convocada y creada por la escritora Pilar V\u00e9lez, presidenta de Snow Fountain Press y directora Ejecutiva del Cap\u00edtulo AIPEH Miami de la Asociaci\u00f3n Internacional de Poetas y Escritores Hispanos-Asociaci\u00f3n Internacional de Arte y Cultura Hispana, con el prop\u00f3sito de celebrar la literatura hispana y a sus gestores mediante un sinn\u00famero de eventos de tipo art\u00edstico-cultural que promueven la lectura, la escritura, y por supuesto, a los escritores hispanos.<\/p>\n<p style=\"text-align: justify;\">Esta iniciativa es apoyada en primera instancia por AIPEH y su red de cap\u00edtulos y embajadores con presencia en cinco continentes, adem\u00e1s de un grupo de Embajadores de Buena Voluntad, en su mayor\u00eda escritores que residen en diferentes ciudades del mundo, y que se unen a esta celebraci\u00f3n con el \u00e1nimo de promover la literatura, la cultura, el uso del idioma espa\u00f1ol en sus comunidades y apoyar diferentes causas sociales que defiende esta celebraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La Celebraci\u00f3n Internacional del Mes del Libro Hispano se realiza en el marco de la celebraci\u00f3n del Mes de la Hispanidad o Mes de la Herencia Hispana; festividad que tiene sus inicios en 1968 bajo el mandato del Presidente Lyndon B. Johnson y que se celebra en los Estados Unidos en reconocimiento al aporte cultural de los hispanos.<\/p>\n<p style=\"text-align: justify;\">Durante un mes, los escritores hispanos \u2013est\u00e9n donde est\u00e9n- cuentan con un marco internacional para convocar a la comunidad en torno a un inter\u00e9s com\u00fan: Los libros escritos por autores hispanos y la importancia de fomentar la lectura y la escritura creativa en nuestro idioma. Son 30 d\u00edas en los que se convoca a la comunidad hispana para que realice diferentes tipos de actividades, entre ellas figuran: Presentaciones de libros, galas literarias, expo ferias de libros, recitales po\u00e9ticos, conversatorios y cert\u00e1menes literarios.<\/p>\n<p style=\"text-align: justify;\">El \u00e9xito de la Celebraci\u00f3n Internacional del Mes del Libro Hispano es posible gracias al respaldo de personas que apoyan la causa cultural, al igual que la gesti\u00f3n de grupos literarios, c\u00edrculos de lectura, organizaciones culturales y comunitarias y las instituciones p\u00fablicas y privadas. Unidos, promovemos la cultura, rescatamos nuestras tradiciones y afianzamos los valores en nuestra sociedad.<\/p>\n<p style=\"text-align: justify;\">Esta es una oportunidad \u00fanica para promover y apoyar el trabajo de nuestros autores y escritores y fomentar la lectura y nuestra literatura. Para participar como instituci\u00f3n o entidad educativa o c\u00edvica-cultural debes:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Permitir al portador de esta comunicaci\u00f3n a efectuar por lo menos un evento con motivo del Mes del Libro Hispano, en el periodo establecido e informar su intenci\u00f3n con 5 d\u00edas de antelaci\u00f3n al mismo.<\/li>\n<li style=\"text-align: justify;\">El evento debe ser reportado con anterioridad para que sea colocado en la Agenda Internacional de Eventos.<\/li>\n<li style=\"text-align: justify;\">Se debe incluir el logo del Mes del Libro Hispano y el de AIPEH-PR en el material que se utilice para promocionar el evento.<\/li>\n<li style=\"text-align: justify;\">Puede tratarse de: presentaciones de libros, galas, charlas, tertulias, concursos, entrevistas, foros, paneles, etc.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3400\" src=\"https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015.jpg\" alt=\"logo-aipeh-pr-brdefinicion-02-015\" width=\"395\" height=\"433\" srcset=\"https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015.jpg 678w, https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015-228x250.jpg 228w, https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015-11x12.jpg 11w, https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015-624x685.jpg 624w, https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015-22x24.jpg 22w, https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015-33x36.jpg 33w, https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015-44x48.jpg 44w, https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015-380x417.jpg 380w, https:\/\/milibrohispano.org\/wp-content\/uploads\/2016\/09\/Logo-AIPEH-PR-brdefinici\u00f3n-02-015-600x658.jpg 600w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><\/p>\n<p style=\"text-align: justify;\">La Asociaci\u00f3n Internacional de Poetas y Escritores Hispanos (AIPEH) es una entidad sin fines de lucro que tiene entre sus principales objetivos fomentar y promover todo lo relacionado a las artes y la cultura hispana en sus distintas expresiones, as\u00ed como reconocer y apoyar a sus principales exponentes.<\/p>\n<p style=\"text-align: justify;\">El cap\u00edtulo de AIPEH Puerto Rico se une a esta celebraci\u00f3n para de alg\u00fan modo aportar al crecimiento de la industria del libro y para ayudar a fomentar el h\u00e1bito de la lectura tanto en los ni\u00f1os como en los adultos.<\/p>\n<p style=\"text-align: justify;\">AIPEH cuenta con cap\u00edtulos en Orlando y Miami en el Estado de la Florida, as\u00ed como en la ciudad de Nueva York, Puerto Rico, Rep\u00fablica Dominicana, Per\u00fa, Argentina y otros. Para mayor informaci\u00f3n acerca de las actividades, puede acceder a: www.aipeh.org \u00f3 escribir a: aipehpr2015@gmail.com<\/p>\n<p style=\"text-align: justify;\">Cordialmente,<\/p>\n<p style=\"text-align: justify;\">Juan F. Cruz Torres, Director Ejecutivo<\/p>\n<p style=\"text-align: justify;\">Ana Delgado, Secretaria<\/p>\n<blockquote>\n<p style=\"text-align: right;\">Apoyar lo que nos enaltece y nos une es una responsabilidad suprema y privilegio para quien se siente orgulloso de su origen y de su patria<\/p>\n<p style=\"text-align: right;\"><em>Juan F. Cruz Torres<\/em><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Como en a\u00f1os anteriores, AIPEH-PR se ha unido a la celebraci\u00f3n del Libro Hispano comprendido entre el 15 de septiembre y el 15 de octubre. La Celebraci\u00f3n Internacional del Mes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[359,478,479,480],"tags":[646,440,366],"class_list":["post-3397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aipeh-miami","category-celebracion-2016","category-hhlo","category-milibrohispano","tag-asociacion-internacional-de-poetas-y-escritores-hispanos-aipeh","tag-celebracion-internacional-del-mes-del-libro-hispano","tag-mes-del-libro-hispano"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/posts\/3397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/comments?post=3397"}],"version-history":[{"count":0,"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/posts\/3397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/media\/3400"}],"wp:attachment":[{"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/media?parent=3397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/categories?post=3397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/milibrohispano.org\/en\/wp-json\/wp\/v2\/tags?post=3397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}